{"id":52,"date":"2017-07-05T16:00:36","date_gmt":"2017-07-05T20:00:36","guid":{"rendered":"http:\/\/facfan.draconis.ufms.br\/?page_id=52"},"modified":"2023-06-06T16:06:06","modified_gmt":"2023-06-06T20:06:06","slug":"projetos-de-pesquisa","status":"publish","type":"page","link":"https:\/\/fach.ufms.br\/en\/projetos-de-pesquisa\/","title":{"rendered":"Projetos de Pesquisa"},"content":{"rendered":"<strong>Linhas de Pesquisa<\/strong><\/p>\n<p>&#8230;","protected":false},"excerpt":{"rendered":"<p>Linhas de Pesquisa &#8230;<\/p>\n","protected":false},"author":7449,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"coauthors":[],"class_list":["post-52","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/fach.ufms.br\/en\/wp-json\/wp\/v2\/pages\/52","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fach.ufms.br\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fach.ufms.br\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fach.ufms.br\/en\/wp-json\/wp\/v2\/users\/7449"}],"replies":[{"embeddable":true,"href":"https:\/\/fach.ufms.br\/en\/wp-json\/wp\/v2\/comments?post=52"}],"version-history":[{"count":1,"href":"https:\/\/fach.ufms.br\/en\/wp-json\/wp\/v2\/pages\/52\/revisions"}],"predecessor-version":[{"id":2717,"href":"https:\/\/fach.ufms.br\/en\/wp-json\/wp\/v2\/pages\/52\/revisions\/2717"}],"wp:attachment":[{"href":"https:\/\/fach.ufms.br\/en\/wp-json\/wp\/v2\/media?parent=52"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/fach.ufms.br\/en\/wp-json\/wp\/v2\/coauthors?post=52"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}